{"id":108,"count":1,"description":"","link":"https:\/\/muziekpers-pressemusicale.be\/fr\/tag\/piet-swerts\/","name":"Piet Swerts","slug":"piet-swerts","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/muziekpers-pressemusicale.be\/fr\/wp-json\/wp\/v2\/tags\/108","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/muziekpers-pressemusicale.be\/fr\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/muziekpers-pressemusicale.be\/fr\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/muziekpers-pressemusicale.be\/fr\/wp-json\/wp\/v2\/posts?tags=108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}