{"id":1733,"date":"2025-11-07T18:49:20","date_gmt":"2025-11-07T17:49:20","guid":{"rendered":"https:\/\/muziekpers-pressemusicale.be\/?p=1733"},"modified":"2026-02-11T18:50:51","modified_gmt":"2026-02-11T17:50:51","slug":"alexandre-melnikov-et-ioulia-lejneva-servent-brillamment-rachmaninov-en-sa-demeure","status":"publish","type":"post","link":"https:\/\/muziekpers-pressemusicale.be\/fr\/alexandre-melnikov-et-ioulia-lejneva-servent-brillamment-rachmaninov-en-sa-demeure\/","title":{"rendered":"Alexandre Melnikov et Ioulia Lejneva servent brillamment Rachmaninov en sa demeure"},"content":{"rendered":"<p>Ce nouvel enregistrement est un \u00e9v\u00e9nement \u00e0 plus d\u2019un titre. Pour commencer il a \u00e9t\u00e9 enregistr\u00e9 \u00e0 la Villa Senar, la belle demeure moderniste que Serge Rachmaninoff\u00a0 -qui \u00e9crivait \u00e0 l\u2019\u00e9poque invariablement son nom de cette fa\u00e7on, graphie qu\u2019a reprise la Fondation Serge Rachmaninoff\u00a0 qui g\u00e8re aujourd\u2019hui cette villa entour\u00e9e d\u2019un parc de deux hectares- fit construire \u00e0 Weggis sur le Lac des Quatre-Cantons, \u00e0 deux pas de Lucerne,\u00a0 entre 1931 et 1933. C\u2019est ici qu\u2019il passa d\u2019heureuses et fructueuses ann\u00e9es et composa la Rhapsodie sur un th\u00e8me de Paganini et sa Troisi\u00e8me Symphonie. Malheureusement la Deuxi\u00e8me Guerre mondiale le surprit en 1939 en pleine tourn\u00e9e aux Etats-Unis, pays qu\u2019il ne quitta plus jusqu\u2019\u00e0 sa mort en Californie en 1943.<\/p>\n\n\n\n<div class=\"wp-block-buttons has-custom-font-size has-medium-font-size is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-a89b3969 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--1\"><a class=\"wp-block-button__link has-white-color has-text-color has-background has-text-align-center wp-element-button\" href=\"https:\/\/www.crescendo-magazine.be\/alexandre-melnikov-et-ioulia-lejneva-servent-brillamment-rachmaninov-en-sa-demeure\/\" style=\"border-radius:0px;background-color:#0f24b4;text-transform:uppercase\" target=\"_blank\" rel=\"noreferrer noopener\">Pour En Lire Plus<\/a><\/div>\n<\/div>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Ce nouvel enregistrement est un \u00e9v\u00e9nement \u00e0 plus d\u2019un titre. Pour commencer il a \u00e9t\u00e9 enregistr\u00e9 \u00e0 la Villa Senar, la belle demeure moderniste que Serge Rachmaninoff\u00a0 -qui \u00e9crivait \u00e0 l\u2019\u00e9poque invariablement son nom de cette fa\u00e7on, graphie qu\u2019a reprise la Fondation Serge Rachmaninoff\u00a0 qui g\u00e8re aujourd\u2019hui cette villa entour\u00e9e d\u2019un parc de deux hectares- [&hellip;]<\/p>","protected":false},"author":5,"featured_media":1734,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,43],"tags":[64,116],"class_list":["post-1733","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cd","category-reviews","tag-harmonia-mundi","tag-rachmaninov"],"_links":{"self":[{"href":"https:\/\/muziekpers-pressemusicale.be\/fr\/wp-json\/wp\/v2\/posts\/1733","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/muziekpers-pressemusicale.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/muziekpers-pressemusicale.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/muziekpers-pressemusicale.be\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/muziekpers-pressemusicale.be\/fr\/wp-json\/wp\/v2\/comments?post=1733"}],"version-history":[{"count":1,"href":"https:\/\/muziekpers-pressemusicale.be\/fr\/wp-json\/wp\/v2\/posts\/1733\/revisions"}],"predecessor-version":[{"id":1735,"href":"https:\/\/muziekpers-pressemusicale.be\/fr\/wp-json\/wp\/v2\/posts\/1733\/revisions\/1735"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/muziekpers-pressemusicale.be\/fr\/wp-json\/wp\/v2\/media\/1734"}],"wp:attachment":[{"href":"https:\/\/muziekpers-pressemusicale.be\/fr\/wp-json\/wp\/v2\/media?parent=1733"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/muziekpers-pressemusicale.be\/fr\/wp-json\/wp\/v2\/categories?post=1733"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/muziekpers-pressemusicale.be\/fr\/wp-json\/wp\/v2\/tags?post=1733"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}