{"id":945,"date":"2024-04-09T14:22:34","date_gmt":"2024-04-09T12:22:34","guid":{"rendered":"https:\/\/muziekpers-pressemusicale.be\/?page_id=945"},"modified":"2024-04-11T08:48:49","modified_gmt":"2024-04-11T06:48:49","slug":"cecilia-prijzen-2023","status":"publish","type":"page","link":"https:\/\/muziekpers-pressemusicale.be\/fr\/cecilia-prijzen-2023\/","title":{"rendered":"Prix Caecilia | 2023"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"945\" class=\"elementor elementor-945\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f160ed9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f160ed9\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5e6e956\" data-id=\"5e6e956\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ef9ae1d elementor-widget elementor-widget-heading\" data-id=\"ef9ae1d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Prix Caecilia | 2023<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-595070e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"595070e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-df8e3c7\" data-id=\"df8e3c7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d89d424 elementor-widget elementor-widget-spacer\" data-id=\"d89d424\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4782959\" data-id=\"4782959\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d07a25e elementor-toc--content-ellipsis elementor-toc--minimized-on-tablet elementor-widget elementor-widget-table-of-contents\" data-id=\"d07a25e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;headings_by_tags&quot;:[&quot;h2&quot;],&quot;exclude_headings_by_selector&quot;:[],&quot;collapse_subitems&quot;:&quot;yes&quot;,&quot;marker_view&quot;:&quot;numbers&quot;,&quot;no_headings_message&quot;:&quot;Er zijn geen kopteksten gevonden op deze pagina.&quot;,&quot;minimize_box&quot;:&quot;yes&quot;,&quot;minimized_on&quot;:&quot;tablet&quot;,&quot;hierarchical_view&quot;:&quot;yes&quot;,&quot;min_height&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;min_height_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;min_height_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"table-of-contents.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toc__header\">\n\t\t\t<h4 class=\"elementor-toc__header-title\">\n\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t<div class=\"elementor-toc__toggle-button elementor-toc__toggle-button--expand\" role=\"button\" tabindex=\"0\" aria-controls=\"elementor-toc__d07a25e\" aria-expanded=\"true\" aria-label=\"Open inhoudsopgave\"><\/div>\n\t\t\t\t<div class=\"elementor-toc__toggle-button elementor-toc__toggle-button--collapse\" role=\"button\" tabindex=\"0\" aria-controls=\"elementor-toc__d07a25e\" aria-expanded=\"true\" aria-label=\"Sluit inhoudsopgave\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t<div id=\"elementor-toc__d07a25e\" class=\"elementor-toc__body elementor-toc__list-items--collapsible\">\n\t\t\t<div class=\"elementor-toc__spinner-container\">\n\t\t\t\t<i class=\"elementor-toc__spinner eicon-animation-spin eicon-loading\" aria-hidden=\"true\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-33c4a6d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"33c4a6d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e583409\" data-id=\"e583409\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-540c61b elementor-widget elementor-widget-heading\" data-id=\"540c61b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Prix du Jeune Musicien de l\u2019ann\u00e9e<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c51bcd2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c51bcd2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-ebc6fdd\" data-id=\"ebc6fdd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8c8ed3b elementor-widget elementor-widget-spacer\" data-id=\"8c8ed3b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-ed525da\" data-id=\"ed525da\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1598e45 elementor-widget elementor-widget-heading\" data-id=\"1598e45\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Liste des artistes nomin\u00e9s pour le Prix du Jeune Musicien de l\u2019Ann\u00e9e 2023 (FR)\n<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd7dfe3 elementor-widget elementor-widget-text-editor\" data-id=\"dd7dfe3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\"><i><i> Le Prix du Jeune Musicien de l\u2019Ann\u00e9e est attribu\u00e9 alternativement \u00e0 un(e) artiste n\u00e9erlandophone et \u00e0 un(e) artiste francophone ou germanophone. <\/i><\/i><\/p><p class=\"p3\">Fiona &amp; Chiara Alaimo, piano<\/p><p class=\"p3\">Pierre Fontenelle, cello<\/p><p class=\"p3\">Juliette Gauthier, harpe<\/p><p class=\"p3\">Maya Levy, violon<\/p><p class=\"p3\">Maxime Melnik, t\u00e9nor<\/p><p class=\"p3\">Pierre Risopoulos, piano &amp; composition<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-a0d33b8\" data-id=\"a0d33b8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c0c926 elementor-widget elementor-widget-spacer\" data-id=\"3c0c926\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-158af7e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"158af7e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-9125ec6\" data-id=\"9125ec6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-13a6772 elementor-widget elementor-widget-image\" data-id=\"13a6772\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/elementor\/thumbs\/IMG_1-scaled-qmgaje2u373vz5nzjstc0knvjtby1rpztos23zrbc0.jpg\" title=\"IMG_1\" alt=\"IMG_1\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\"><\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-e384acc\" data-id=\"e384acc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-803529b elementor-widget elementor-widget-heading\" data-id=\"803529b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Laur\u00e9ate<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-616a5f2 elementor-widget elementor-widget-text-editor\" data-id=\"616a5f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">N\u00e9e en 1997 d\u2019un p\u00e8re fran\u00e7ais et d\u2019une m\u00e8re belge, Maya Levy a commenc\u00e9 \u00e0 jouer du violon \u00e0 l'\u00e2ge de 4 ans sous la direction de Bernadette Jansen. Elle a poursuivi ses \u00e9tudes avec Igor Tkatchouk et, depuis 2013, elle travaille avec Boris Kuschnir \u00e0 Vienne. Au cours de sa formation, elle a particip\u00e9 aux masterclasses de nombreux professeurs de renom, tels Augustin Dumay, Pavel Vernikov, Itamar Golan, Renaud Capu\u00e7on, Miriam Fried, Andrei Baranov, Sergey Khachatryan et Leonidas Kavakos.<\/p><p class=\"p1 translation-block\">Distingu\u00e9e par des prix prestigieux - citons le 1er prix des M\u00e9dias Francophones Publics 2020, le titre d\u2019Artiste de l\u2019ann\u00e9e 2022 de la RTBF, une m\u00e9daille d'argent \u00e0 la Manhattan International Music Competition, le prix Supernova au Festival Klara -, Maya Levy est laur\u00e9ate de plusieurs grands concours, tels le concours Karol Szymanowski (2018) ou le concours Karol Lipinski (2019). En 2021, elle a jou\u00e9 lors du concert d'adieu de la chanceli\u00e8re allemande Angela Merkel, au Palais des Beaux-Arts de Bruxelles.<\/p><p class=\"p1\">Elle s\u2019est produite avec de nombreux chefs d'orchestre et orchestres de renom, notamment l'Orchestre symphonique national de la Radio polonaise, l'Orchestre royal de chambre de Wallonie, l'Orchestre symphonique de Torun, la Mitteldeutsche Kammerphilharmonie, et dans des lieux tels que le Konzerthaus de Berlin, la salle de concert NOSPR en Pologne, la salle symphonique de la Philharmonie de Szczecin, Flagey, La Monnaie ou Bozar \u00e0 Bruxelles, De Bijloke \u00e0 Gand, la Salle Philharmonique de Li\u00e8ge, le Conservatoire Tcha\u00efkovski de Moscou ou la salle de concert Recanati \u00e0 Tel Aviv.<\/p><p class=\"p1\">Maya wordt regelmatig op festivals uitgenodigd: Les Sommets Musicaux te Gstaad (Zwitserland), het<span class=\"Apple-converted-space\">\u00a0 <\/span>Maya est r\u00e9guli\u00e8rement invit\u00e9e dans des festivals tels que Les Sommets Musicaux de Gstaad (Suisse), le Festival Mozartiana de Gdansk (Pologne), le Festival de l'Et\u00e9 mosan, le Klarafestival ou le Festival Musiq\u20193 (Belgique), o\u00f9 elle appara\u00eet avec des artistes tels que Rolando Villazon, Julien Quentin, Boris Kusnezow, Alexander Mogilevsky, Mariusz Smolij, Rune Bergmann, Andrei Gridchuk, Omar Massa, etc. Sa prochaine saison s\u2019ouvrira par une tourn\u00e9e en Chine, suivie de concerts en Espagne, Italie, Lituanie, Isra\u00ebl, France et Belgique.<\/p><p class=\"p1\">\u00c9galement passionn\u00e9e de musique de chambre, Maya a form\u00e9 un duo avec le pianiste Matthieu Idmtal pendant sept ans et fit partie du Trio Carlo Van Neste pendant dix ans. Publi\u00e9s chez Pavane, deux CD sont n\u00e9s de ces collaborations\u00a0: l'int\u00e9grale des Trios \u00e0 clavier de Mendelssohn (2014) et les sonates compl\u00e8tes pour violon et piano d'Edvard Grieg avec le pianiste Matthieu Idmtal (2017) \u2013 ce dernier CD, r\u00e9compens\u00e9 par le magazine Classica, le Strad Magazine et le top 10 de Klara. En 2021, en duo avec le violoniste Hrachya Avanesyan, Maya a enregistr\u00e9 un CD intitul\u00e9 The Lockdown, consacr\u00e9 \u00e0 Piazzolla et Prokofiev (Rubicon Classics Ltd. \u00e0 Londres). <i>The Lockdown,<\/i> met werken voor twee violen van Piazzolla en Prokofiev (uitgegeven bij Rubicon Classics Ltd., Londen).<\/p><p class=\"p1\">Maya joue sur un violon Guarneri (Cremona) de 1702.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3fc3a41 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3fc3a41\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2c989c4\" data-id=\"2c989c4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b9a16f5 elementor-widget elementor-widget-heading\" data-id=\"b9a16f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Prix Caecilia<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e828d93 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e828d93\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-2c00485\" data-id=\"2c00485\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b8de9e7 elementor-widget elementor-widget-spacer\" data-id=\"b8de9e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-113a1c5\" data-id=\"113a1c5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fcd6828 elementor-tabs-view-vertical elementor-widget elementor-widget-tabs\" data-id=\"fcd6828\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-2651\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-2651\" aria-expanded=\"false\">Prix Caecilia<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-2652\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2652\" aria-expanded=\"false\">Liste des enregistrements nomin\u00e9s<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-2651\" aria-expanded=\"false\">Prix Caecilia<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2651\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2651\" tabindex=\"0\" hidden=\"false\"><p class=\"p2\">Comment l\u2019Union de la Presse Musicale Belge proc\u00e8de-t-elle \u00e0 la d\u00e9signation des laur\u00e9ats\u00a0?<\/p><ol class=\"ol1\"><li class=\"li1\">Chaque membre de l\u2019UPMB envoie la liste de ses CDs et DVDs favoris, publi\u00e9s au cours de l\u2019ann\u00e9e \u00e9coul\u00e9e (en l\u2019occurrence du 15 d\u00e9cembre 2022 au 31 d\u00e9cembre 2023), avec un minimum de 10 et un maximum de 40 enregistrements. \u00a0<\/li><li class=\"li1\">Le jury d\u00e9pouille et classe les suffrages et se laisse un d\u00e9lai pour compl\u00e9ter ses informations (commander, r\u00e9partir et \u00e9couter les enregistrements nomin\u00e9s).<\/li><li class=\"li2\">Lors d\u2019une seconde r\u00e9union, 10 enregistrements (CDs et DVDs confondus) sont d\u00e9sign\u00e9s comme Prix Caecilia, auxquels peuvent s\u2019ajouter le Prix Snepvangers, d\u00e9signant une production de musique belge, le Prix Sp\u00e9cial, qui permet de r\u00e9compenser un \u2018coup de c\u0153ur\u2019 du jury, le Prix Albert De Sutter, d\u00e9signant une \u00e9dition\u00a0historique, ainsi qu\u2019un prix r\u00e9compensant la carri\u00e8re d\u2019un interpr\u00e8te ou compositeur.<\/li><\/ol><p class=\"p1\">Sans \u00e9carter les grandes productions internationales de prestige, le jury des Prix Caecilia s\u2019efforce de mettre \u00e0 l\u2019honneur les nouveaux talents, les r\u00e9pertoires rares, les projets audacieux.<\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2652\" aria-expanded=\"false\">Liste des enregistrements nomin\u00e9s<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2652\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2652\" tabindex=\"0\" hidden=\"hidden\"><h4 class=\"p1\">Liste des enregistrements nomin\u00e9s, <br \/>par ordre chronologique des compositeurs<\/h4><p class=\"p1\"><i>Oriente Lux &#8211;<\/i> <span class=\"s1\">Waed Bouhassoun<\/span> &#8211; <span class=\"s1\">Moslem Rahal<\/span><span class=\"s1\"> &#8211;<\/span> Orpheus 21 &#8211; Hesp\u00e8rion XXI &#8211; Jordi Savall &#8211; Alia Vox<\/p><p class=\"p1\"><i>Gratia Plena (To Memling)<\/i> &#8211; Comp\u00e8re, Dufay, Memling, Mouton, Obrecht &#8211; Psallentes &amp; The Royal Wind Music &#8211; Hendrik Vanden Abeele &#8211; Le Bricoleur<\/p><p class=\"p1\">Josquin Desprez, <i>Motets &amp; Chansons &#8211; <\/i>Cut Circle &#8211; Jesse Rodin &#8211; Musique en Wallonie<\/p><p class=\"p3\"><span class=\"s2\">John Dowland, <i>[Complete] Lachrimae<\/i> &#8211; <\/span><span class=\"s1\">Musicall Humors &#8211; Myriam Rignol &#8211; Lucile Boulanger &#8211; Julien Leonard &#8211; Nicholas Milne &#8211; Josh Cheatham &#8211; Thomas Dunford<\/span><span class=\"s2\"> \u2013 Alpha Classics<\/span><\/p><p class=\"p1\"><i>Ein Deutsches Barockrequiem <\/i>&#8211; Briegel, F\u00f6rtsch, Geist, Harmmerschmidt, Michael, Scharmann, Schein, Schwemmer &#8211; Vox Luminis &#8211; Lionel Meunier &#8211; Ricercar<\/p><p class=\"p1\">Jean-Baptiste Lully, <i>Psych\u00e9 <\/i>&#8211; Ambroisine Br\u00e9 &#8211; D\u00e9borah Cachet &#8211; B\u00e9n\u00e9dicte Tauran &#8211; Eug\u00e9nie Lefevre &#8211; Cyril Auvity &#8211; Robert Getchell &#8211; Zacharie Wilder &#8211; Fabien Hyon &#8211; Philippe Est\u00e8phe &#8211; Anas S\u00e9guin &#8211; Matthieu Heim &#8211; Dominique Bonnetain &#8211; Beno\u00eet Porcherot &#8211; Les Talens Lyriques &#8211; Christophe Rousset &#8211; Ch\u00e2teau de Versailles<\/p><p class=\"p1\">Dietrich Buxtehude, <i>Salvador Mundi<\/i> &#8211; Ricercar Consort &#8211; Philippe Pierlot &#8211; Mirare<\/p><p class=\"p4\"><span class=\"s2\">Marc-Antoine Charpentier, <i>David &amp; Jonathas <\/i>&#8211; <\/span><span class=\"s1\">Reinoud Van Mechelen &#8211; Caroline Arnaud &#8211; David Witczak &#8211; Fran\u00e7ois-Olivier Jean &#8211; Antonin Rondepierre &#8211; Geoffroy Buffi\u00e8re &#8211; Virgile Ancely &#8211;<\/span><span class=\"s2\"> Ensemble Marguerite Louise &#8211; Ga\u00ebtan Jarry &#8211; Ch\u00e2teau de Versailles<\/span><\/p><p class=\"p1\"><i>Mystery Sonatas &#8211; <\/i>Heinrich Ignaz Franz Biber<i> <\/i>&#8211; Ensemble Cordaria &#8211; Amandine Beyer &#8211; Gli Incogniti &#8211; Harmonia Mundi<\/p><p class=\"p1\"><i>Beyond &#8211; <\/i>Bernabei, Caccini, Cappellini, Cavalli, Frescobaldi, Jarz\u0119bski, Kapsberger, Marini, Monteverdi, Moratelli, Netti, Pallavicino, Pollarolo, Saracini, Sartorio, Strozzi, Vitali, Kerll<i> &#8211; <\/i>Jakub J\u00f3zef Orli\u0144ski &#8211; Il Pomo d\u2019Oro &#8211; Erato<\/p><p class=\"p1\"><i>Bach &amp; l\u2019Italie<\/i> &#8211; J.S. Bach, Marcello, A. Scarlatti, Vivaldi &#8211; Justin Taylor &#8211; Alpha Classics<\/p><p class=\"p1\">Johann Sebastian Bach, <i>Cello Suites Nos. 3 &amp; 4 &#8211; <\/i>Sonia Wieder-Atherton &#8211; Alpha Classics<\/p><p class=\"p1\">Johann Sebastian Bach, <i>Musicalisches Opfer &#8211; <\/i>Ausonia &#8211; Fr\u00e9d\u00e9rick Haas &#8211; Hitasura<\/p><p class=\"p1\"><i>Music for Cello &amp; Piano &#8211;<\/i> J.S. Bach, Debussy, Faur\u00e9, Lysight, Prokofiev, Rachmaninov, Saint-Sa\u00ebns, Schumann, Ysa\u00ffe &#8211;<i> <\/i>Aleksandr Khramouchin &#8211; Eliane Reyes \u2013 Et\u2019cetera<\/p><p class=\"p3\"><span class=\"s2\">George Frideric H\u00e4ndel, <i>Messiah <\/i>&#8211; <\/span><span class=\"s1\">Lucy Crowe &#8211; Alex Potter &#8211; Michael Spyres &#8211; Matthew Brook &#8211; Rory McCleery &#8211; Choir of The English Concert &#8211; The English Concert &#8211; John Nelson &#8211; <\/span><span class=\"s2\">Erato<\/span><\/p><p class=\"p1\"><i>Sonate a quattro<\/i> &#8211; Fasch, H\u00e4ndel, Janitsch, Goldberg, Telemann &#8211; Ensemble Diderot &#8211; Johannes Pramsohler &#8211; Audax<\/p><p class=\"p5\"><i>Il Virtuoso, Il Poeta &#8211; <\/i>Pietro Antonio Locatelli, <i>Violin Concertos &amp; Concerti Grossi<\/i> &#8211; <a href=\"https:\/\/www.bol.com\/be\/nl\/c\/il-giardino-armonico-isabelle-faust\/606041528\/\">Isabelle Faust<\/a> &#8211; Il Giardino Armonico &#8211; Giovanni Antonini &#8211; Harmonia Mundi<\/p><p class=\"p1\"><i>Contra-Tenor &#8211; <\/i>Galuppi, Gluck, H\u00e4ndel, Hasse, Latilla, Lully, Mazzoni, Mozart, Piccinni, Porpora, Rameau, Sarro, Vinci, Vivaldi &#8211; Michael Spyres &#8211; Il Pomo d\u2019Oro &#8211; Francesco Corti &#8211; Erato<\/p><p class=\"p1\">Joseph Haydn, <i>Stabat Mater<\/i> &#8211; Kristina Hammarstr\u00f6m &#8211;\u00a0Birgitte Christensen &#8211; Kammerorchester B\u00e4sel &#8211;\u00a0Z\u00fcrcher Sing-Akademie &#8211; Ren\u00e9 Jacobs &#8211; Pentatone<\/p><p class=\"p1\">Wolfgang Amadeus Mozart, <i>String Quintets <\/i>K.515 &amp; K.516<i> &#8211; <\/i>Antoine Tamestit \u2013 Quatuor \u00c9b\u00e8ne &#8211; Erato<\/p><p class=\"p1\">Franz Schubert, <i>Die sch\u00f6ne M\u00fcllerin<\/i> &#8211; Samuel Hasselhorn &#8211; Ammiel Bushakevitz &#8211; Harmonia Mundi<\/p><p class=\"p5\">Franz Schubert, <i>Symphonies Nos. 5 &amp; 7 \u2018Unfinished\u2019 <\/i>&#8211; Freiburger Barockorchester &#8211; Pablo Heras-Casado &#8211; Harmonia Mundi<\/p><p class=\"p1\">Franz Schubert &#8211; <i>Piano Trios, Notturno, Rondo &amp; Arpeggione Sonata<\/i> &#8211; Christian Tetzlaff &#8211; Tanja Tetzlaff &#8211; Lars Vogt &#8211; Ondine<\/p><p class=\"p1\"><i>The Chopin Project: Trilogy &#8211; <\/i>Chopin, Franchomme &#8211; Camille Thomas &#8211; Julien Brocal &#8211; Deutsche Grammophon<\/p><p class=\"p1\">Robert Schumann, Maurice Ravel &#8211; <i>String Quartets &#8211; <\/i>Leonkoro Quartet &#8211; Mirare<\/p><p class=\"p1\">Franz Liszt, <i>Transcendental Etudes &amp; Piano Sonata<\/i> &#8211; Francesco Piemontesi &#8211; Pentatone<\/p><p class=\"p1\">Jacques Offenbach, <i>La Princesse de Trebizonde<\/i> &#8211; Antoinette Dennefeld &#8211; Anne-Catherine Gillet &#8211; Josh Lovell &#8211; Virginie Verrez &#8211; London Philharmonic Orchestra &#8211; Opera Rara Chorus &#8211; Paul Daniel &#8211; Opera Rara<\/p><p class=\"p1\">C\u00e9sar Franck, <i>Hulda <\/i>&#8211; Ch\u0153ur de Chambre de Namur &#8211; Orchestre Philharmonique Royal de Li\u00e8ge &#8211; Gergely Madaras &#8211; Palazzetto Bru Zane<\/p><p class=\"p1\">Anton Bruckner, <i>Symphony No. 3<\/i> &#8211; <span class=\"s3\">G\u00fcrzenich-Orchester K\u00f6ln\u00a0&#8211; <\/span>Fran\u00e7ois-Xavier Roth &#8211; Myrios<\/p><p class=\"p6\"><span class=\"s2\">Anton Bruckner, <i>Symphony No. 8<\/i> &#8211; <\/span><span class=\"s1\">Tonhalle-Orchester Z\u00fcrich &#8211; Paavo J\u00e4rvi &#8211; Alpha Classics<\/span><\/p><p class=\"p7\"><span class=\"s2\">Anton\u00edn <\/span><span class=\"s4\">Dvo\u0159\u00e1k, <i>The Complete Piano Trios <\/i>&#8211; <\/span>Boris Giltburg &#8211; Veronika Jar\u016f\u0161kov\u00e1 &#8211; Peter Jar\u016f\u0161ek &#8211; <span class=\"s4\">Supraphon<\/span><\/p><p class=\"p1\">Giacomo Puccini, <i>Tosca &#8211; <\/i>Malin Bystr\u00f6m &#8211; Joshua Guerrero &#8211; Gevorg Hakobyan &#8211; Martijn Sanders &#8211; Federico de Michelis &#8211; Lucas van Lierop &#8211; Maksym Nazarenko &#8211; Alexander de Jong &#8211; Chorus of Dutch National Opera &#8211; Netherlands Philharmonic Orchestra &#8211; Lorenzo Viotti<\/p><p class=\"p1\">Giacomo Puccini, <i>Turandot &#8211; <\/i>Gregory Bonfatti &#8211; Ermonela Jaho &#8211; Jonas Kaufmann \u2013<i> <\/i>Siyabonga Maqungo &#8211; Mattia Olivieri &#8211; Michele Pertusi &#8211; Sondra Radvanovsky &#8211; Michael Spyres &#8211; Coro &amp; Orchestra dell\u2019Accademia Nazionale Di Santa Cecilia &#8211;<i> <\/i>Antonio Pappano &#8211; Warner Classics<\/p><p class=\"p1\">Eug\u00e8ne Ysa\u00ffe &#8211; <i>Six Sonatas <\/i>op. 27 <i>&#8211; <\/i>Hilary Hahn &#8211; Deutsche Grammophon<\/p><p class=\"p1\"><i>Alfred Dubois<\/i> &#8211; De Taeye, Franck, Goeyens, Jongen, Nardini, Rogister, Vieuxtemps, Voss, Ysa\u00ffe &#8211; Alfred Dubois &#8211; Musique en Wallonie<\/p><p class=\"p1\"><i>1923<\/i> &#8211; Delius, Achron, Bloch, Eisler, Hauer, Jaques-Dalcroze, Janacek, Klein, Mompou, Schoenberg, Tansman &#8211; Yaara Tal &#8211; Andreas Groethuysen &#8211; Sony Classical<\/p><p class=\"p1\">Ralph Vaughan Williams, <i>Sinfonia Antartica &amp; Symphony No. 9 &#8211; <\/i><span class=\"s1\">Elizabeth Watts &#8211;<\/span> BBC Symphony Orchestra &amp; Chorus &#8211; Martin Brabbins &#8211; Hyperion<\/p><p class=\"p1\"><i>F\u00eates Rouges &#8211; <\/i>Joseph Jongen, <i>Int\u00e9grale des m\u00e9lodies<\/i>,<i> <\/i>vol. 2 &#8211; Sarah Defrise &#8211; Craig White &#8211; Musique en Wallonie<\/p><p class=\"p1\">Maurice Ravel, <i>L\u2019Heure espagnole &amp; Bolero<\/i> &#8211; Les Si\u00e8cles &#8211; Fran\u00e7ois-Xavier Roth &#8211; Harmonia Mundi<\/p><p class=\"p1\">Ottorino Respighi, <i>Gli Uccelli <\/i>&#8211; Orchestre Philharmonique Royal de Li\u00e8ge &#8211; John Neschling &#8211; BIS<\/p><p class=\"p1\">B\u00e9la Bart\u00f3k, <i>Piano Concertos <\/i>&#8211; <span class=\"s5\">Pierre-Laurent Aimard &#8211; <\/span>San Francisco Symphony &#8211; Esa-Pekka Salonen &#8211; Pentatone<\/p><p class=\"p1\">Igor Stravinsky, <i>The Rite of Spring &amp; The Fire Bird <\/i>&#8211; Orchestre de Paris &#8211; Klaus M\u00e4kel\u00e4 &#8211; Decca<\/p><p class=\"p1\"><i>Les Heures Claires<\/i> &#8211; Lili &amp; Nadia Boulanger, <i>The Complete Songs <\/i>&#8211; Lucile Richardot &#8211; Anne de Fornel \u2013 St\u00e9phane Degout &#8211; Raquel Camarinha &#8211; Sarah Nemtanu &#8211; Harmonia Mundi<\/p><p class=\"p1\"><i>Voyage Intime &#8211; <\/i>L. Boulanger, Duparc, Liszt, Schumann, Wolf &#8211;<i> <\/i>Sandrine<i> <\/i>Piau &#8211; David Kadouch<i> <\/i>&#8211; Alpha Classics<\/p><p class=\"p1\">Francis Poulenc, <i>La Voix humaine &amp; Sinfonietta <\/i>&#8211; V\u00e9ronique Gens &#8211; Orchestre National de Lille &#8211; Alexandre Bloch &#8211; Alpha Classics<\/p><p class=\"p1\"><i>The Genius of Django &#8211; <\/i>Django Reinhardt &#8211; Ouest<\/p><p class=\"p5\">Mieczys\u0142aw\u00a0Weinberg, <i>String Quartets Nos. 4 &amp; 16<\/i> &#8211; Arcadia Quartet &#8211; Chandos<\/p><p class=\"p1\">Veljo Tormis, <i>Reminiscentiae &#8211; <\/i>Estonian Philharmonic Chamber Choir &#8211; Tallin Chamber Orchestra &#8211; T\u00f5nu Kaljuste &#8211; ECM<\/p><p class=\"p1\">Philippe Boesmans, <i>On purge b\u00e9b\u00e9 &#8211; <\/i>Jean-S\u00e9bastien Bou &#8211; Jodie Devos &#8211; Denzil Delaere &#8211; La Monnaie Symphony Orchestra &#8211; Bassem Akiki &#8211; Fuga Libera<\/p><p class=\"p1\">Julius Eastman, <i>If You\u2019re So Smart, Why Aren\u2019t You Rich?<\/i> &#8211; Eastman &#8211; Wild Up &#8211; Christopher Rountree &#8211; New Amsterdam Records<\/p><p class=\"p1\"><i>\u00d8rnen 1897 &#8211; <\/i>George De Decker &#8211; Sp!tsbergen &#8211; George De Decker &#8211; Antarctica<\/p><p class=\"p9\"><span class=\"s2\"><i>Reconnaissance &#8211; <\/i>Kaija Saariaho, <i>Choral Music<\/i> &#8211; <\/span>Olli Mustonen &#8211; Lahti Symphony Orchestra &#8211; Helsinki Chamber Choir &#8211; Dalia Stasevska &#8211; BIS<\/p><p class=\"p1\">Thomas Ad\u00e8s, <i>Dante &#8211; <\/i><span class=\"s1\">Los Angeles Master Chorale &amp; Philharmonic &#8211; Gustavo Dudamel &#8211; <\/span>Nonesuch<\/p><p class=\"p1\"><i>S\u2019\u00e9lancer &#8211; <\/i>Adrien Tsilogiannis &#8211; Clara Inglese &#8211; Lorenzo Car\u00f2la &#8211; Ensemble Sturm und Klang &#8211; Thomas Van Haeperen &#8211; Cypres<\/p><p class=\"p1\"><i>Places &#8211;<\/i> B\u00fcs\u0327ra Kay\u0131k\u00e7\u0131 &#8211; B\u00fcs\u0327ra Kay\u0131k\u00e7\u0131 &#8211; Warner Classics<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-8835f2c\" data-id=\"8835f2c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9e068ac elementor-widget elementor-widget-spacer\" data-id=\"9e068ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8782a19 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8782a19\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-23b0a34\" data-id=\"23b0a34\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e98b9c9 elementor-widget elementor-widget-heading\" data-id=\"e98b9c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Prix sp\u00e9ciaux<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5c37eb9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5c37eb9\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5e6652f\" data-id=\"5e6652f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4aa6f29 elementor-flip-box--effect-flip elementor-flip-box--direction-up elementor-widget elementor-widget-flip-box\" data-id=\"4aa6f29\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-flip-box\" tabindex=\"0\">\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__front\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-flip-box__image\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/ab67616d0000b2735260ffa7ca8c83655e330ab4-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail wp-image-959\" alt=\"\" srcset=\"https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/ab67616d0000b2735260ffa7ca8c83655e330ab4-150x150.jpeg 150w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/ab67616d0000b2735260ffa7ca8c83655e330ab4-300x300.jpeg 300w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/ab67616d0000b2735260ffa7ca8c83655e330ab4-12x12.jpeg 12w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/ab67616d0000b2735260ffa7ca8c83655e330ab4.jpeg 640w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-flip-box__layer__title\">\n\t\t\t\t\t\t\t\tPrix Albert De Sutter\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__back\">\n\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-flip-box__layer__title\">\n\t\t\t\t\t\t\tMusique en Wallonie\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-flip-box__layer__description\">\n\t\t\t\t\t\t\t<b>Alfred Dubois<br><\/b>\nDe Taeye, Franck, Goeyens, Jongen, Nardini, Rogister, Vieuxtemps, Voss, Ysa\u00ffe <br>\n1 CD Musique en Wallonie\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-a33e176\" data-id=\"a33e176\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4664a54 elementor-flip-box--effect-flip elementor-flip-box--direction-up elementor-widget elementor-widget-flip-box\" data-id=\"4664a54\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-flip-box\" tabindex=\"0\">\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__front\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-flip-box__image\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/KTC-1802-front-small-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-958\" alt=\"\" srcset=\"https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/KTC-1802-front-small-150x150.jpg 150w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/KTC-1802-front-small-13x12.jpg 13w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-flip-box__layer__title\">\n\t\t\t\t\t\t\t\tHommage\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__back\">\n\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-flip-box__layer__title\">\n\t\t\t\t\t\t\tEt\u2019cetera\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-flip-box__layer__description\">\n\t\t\t\t\t\t\t<i>Music for Cello &amp; Piano<br><\/i>\nJ.S. Bach, Debussy, Faur\u00e9, Lysight, Prokofiev, Rachmaninov, Saint-Sa\u00ebns, Schumann, Ysa\u00ffe\nAleksandr Khramouchin \/ Eliane Reyes<br>\n1 CD Et\u2019cetera<br>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7b4cb28\" data-id=\"7b4cb28\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9c6aa2e elementor-flip-box--effect-flip elementor-flip-box--direction-up elementor-widget elementor-widget-flip-box\" data-id=\"9c6aa2e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-flip-box\" tabindex=\"0\">\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__front\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-flip-box__image\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/5412217046613-front-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-957\" alt=\"\" srcset=\"https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/5412217046613-front-150x150.jpg 150w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/5412217046613-front-300x300.jpg 300w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/5412217046613-front-1024x1024.jpg 1024w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/5412217046613-front-768x768.jpg 768w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/5412217046613-front-12x12.jpg 12w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/5412217046613-front.jpg 1500w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-flip-box__layer__title\">\n\t\t\t\t\t\t\t\tPrix Snepvanger\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__back\">\n\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-flip-box__layer__title\">\n\t\t\t\t\t\t\tCypres\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-flip-box__layer__description\">\n\t\t\t\t\t\t\tAdrien Tsilogiannis<br>\n<i>S\u2019\u00e9lancer<\/i><br>\nEnsemble Sturm und Klang<br>\nThomas Van Haeperen<br>\nClara Inglese, Lorenzo Car\u00f2la<br>\n1 CD Cypres<br>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-73a7863 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"73a7863\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-7bc9e68\" data-id=\"7bc9e68\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d1a287b elementor-widget elementor-widget-spacer\" data-id=\"d1a287b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-5d1a51e\" data-id=\"5d1a51e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2958594 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2958594\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-2d44f6b\" data-id=\"2d44f6b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b8c8417 elementor-widget elementor-widget-image\" data-id=\"b8c8417\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"640\" src=\"https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/ab67616d0000b2735260ffa7ca8c83655e330ab4.jpeg\" class=\"attachment-large size-large wp-image-959\" alt=\"\" srcset=\"https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/ab67616d0000b2735260ffa7ca8c83655e330ab4.jpeg 640w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/ab67616d0000b2735260ffa7ca8c83655e330ab4-300x300.jpeg 300w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/ab67616d0000b2735260ffa7ca8c83655e330ab4-150x150.jpeg 150w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/ab67616d0000b2735260ffa7ca8c83655e330ab4-12x12.jpeg 12w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-3279d54\" data-id=\"3279d54\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5d4c37a elementor-widget elementor-widget-text-editor\" data-id=\"5d4c37a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">Cette parution rend enfin justice \u00e0 Alfred Dubois. Magnifiquement restaur\u00e9s, ces rares enregistrements r\u00e9alis\u00e9s autour de 1930 donnent \u00e0 entendre un artiste rac\u00e9, v\u00e9ritable cha\u00eenon manquant dans l\u2019histoire de l\u2019\u00e9cole belge du violon entre Vieuxtemps et Grumiaux, dont il fut le professeur au Conservatoire de Bruxelles. Dubois impressionne par sa sobri\u00e9t\u00e9, sa subtilit\u00e9, son go\u00fbt exquis comme sa musicalit\u00e9 de tous les instants. Dans ce r\u00e9pertoire belge \u2013 o\u00f9 de s\u00e9duisants morceaux de genre c\u00f4toient une magnifique Sonate de Franck avec le pianiste Marcel Maas et la Troisi\u00e8me sonate d\u2019Ysa\u00ffe \u2013, Dubois impressionne par une aristocratique r\u00e9serve d\u00e9pourvue de tout sentimentalisme, alli\u00e9e \u00e0 une \u00e9motion implicite plut\u00f4t que soulign\u00e9e. (Patrice Lieberman)<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8d7d4d1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8d7d4d1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-e77dcf2\" data-id=\"e77dcf2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6850960 elementor-widget elementor-widget-image\" data-id=\"6850960\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"462\" src=\"https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/KTC-1802-front-small.jpg\" class=\"attachment-large size-large wp-image-958\" alt=\"\" srcset=\"https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/KTC-1802-front-small.jpg 500w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/KTC-1802-front-small-300x277.jpg 300w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/KTC-1802-front-small-13x12.jpg 13w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-45b2099\" data-id=\"45b2099\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2418e21 elementor-widget elementor-widget-text-editor\" data-id=\"2418e21\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"page\" title=\"Page 13\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><p class=\"p1\"><span class=\"s1\">Le 13 mai 2023, une septic\u00e9mie foudroyante emportait le violoncelliste bi\u00e9lorusse Aleksandr Khramouchin, 43 ans. Cl\u00f4turant \u00e0 titre posthume une discographie significative, un album d\u2019hommage fut publi\u00e9 quelques mois plus tard, gr\u00e2ce au label Et\u2019cetera et \u00e0 l\u2019entourage de l\u2019artiste \u2013 \u00e0 commencer par la pianiste Eliane Reyes, son \u00e9pouse et partenaire. Et c\u2019est un petit miracle\u00a0: par la richesse et la diversit\u00e9 des captations r\u00e9centes, toutes enregistr\u00e9es live, par la qualit\u00e9 du mastering, du design et du livret, et enfin, et surtout, par la \u00ab\u00a0voix\u00a0\u00bb d\u2019un musicien \u00e9blouissant, que l\u2019on ne d\u00e9couvre aussi intimement que pour l\u2019avoir perdu. (Martine D. Mergeay)<\/span><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-46fc865 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"46fc865\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-2cbd946\" data-id=\"2cbd946\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ade94d0 elementor-widget elementor-widget-image\" data-id=\"ade94d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/5412217046613-front-1024x1024.jpg\" class=\"attachment-large size-large wp-image-957\" alt=\"\" srcset=\"https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/5412217046613-front-1024x1024.jpg 1024w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/5412217046613-front-300x300.jpg 300w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/5412217046613-front-150x150.jpg 150w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/5412217046613-front-768x768.jpg 768w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/5412217046613-front-12x12.jpg 12w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/5412217046613-front.jpg 1500w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-fe09ecb\" data-id=\"fe09ecb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fddc375 elementor-widget elementor-widget-text-editor\" data-id=\"fddc375\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1 translation-block\">Professeur assistant d\u2019Analyse-\u00c9critures au Conservatoire royal de Bruxelles et de violoncelle \u00e0 l\u2019Acad\u00e9mie de Schaerbeek, Adrien Tsilogiannis est l\u2019un des compositeurs belges les plus dou\u00e9s de sa g\u00e9n\u00e9ration. On discerne dans son langage musical, r\u00e9solument moderne, des traces \u00e9parses de son admiration pour Kaija Saariaho, George Benjamin, Magnus Lindberg et Salvatore Sciarrino. \u00c0 42 ans, cependant, Tsilogiannis ne se laisse plus enfermer dans aucun moule. Dans ses \u0153uvres oniriques, amoncellements de couleurs puisant souvent leurs racines dans la litt\u00e9rature, il est \u00e0 la fois peintre, po\u00e8te et musicien. Cypres fait, une nouvelle fois, preuve de clairvoyance en \u00e9ditant le premier disque monographique consacr\u00e9 \u00e0 cet artiste talentueux. On y retrouve cinq \u0153uvres \u00e9crites entre 2012 et 2022 et cr\u00e9\u00e9es dans la foul\u00e9e par des partenaires ind\u00e9fectibles du compositeur, le prodigieux ensemble Sturm und Klang, dirig\u00e9 de main de ma\u00eetre par Thomas Van Haeperen, la soprano Clara Inglese et le t\u00e9nor Lorenzo Car\u00f2la. Chaque partition repose sur un alliage de timbres diff\u00e9rent et r\u00e9v\u00e8le l\u2019extr\u00eame attention port\u00e9e par cet orf\u00e8vre des sons qu\u2019est Tsilogiannis \u00e0 la diversit\u00e9 des \u00e9clairages, des coloris et des textures instrumentales. La transparence des lignes et du tissu polyphonique, conjugu\u00e9e \u00e0 ce foisonnement de couleurs et \u00e0 un sens aigu du rythme et du mouvement, font de ces partitions moir\u00e9es de v\u00e9ritables fantaisies-tableaux, servies en l\u2019occurrence par une prise de son proche et cristalline. (Olivier Vrins)<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-9197ede\" data-id=\"9197ede\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-07ddf16 elementor-widget elementor-widget-spacer\" data-id=\"07ddf16\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-373e9d4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"373e9d4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8e12eea\" data-id=\"8e12eea\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7002ef9 elementor-widget elementor-widget-heading\" data-id=\"7002ef9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Laur\u00e9ats<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c535d9b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c535d9b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3ff816b\" data-id=\"3ff816b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cef12e6 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"cef12e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;5&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay_speed&quot;:2000,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrousel afbeelding\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 van 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/5054197726453-front.jpg\" alt=\"5054197726453-front\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 van 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/71EX0LYu54L._UF10001000_QL80_.jpg\" alt=\"71EX0LYu54L._UF1000,1000_QL80_\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 van 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/3701624510032-back.jpg\" alt=\"3701624510032-back\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 van 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/1200x1200.jpg\" alt=\"1200x1200\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 van 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/1200x1200-1.jpg\" alt=\"1200x1200\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 van 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/hilary-hahn-ysaye-6-sonatas-for-violin-solo-op-27-1536x1536.jpg\" alt=\"hilary-hahn-ysaye-6-sonatas-for-violin-solo-op-27\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 van 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/1200x1200bb.jpg\" alt=\"1200x1200bb\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 van 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/550x550.jpg\" alt=\"550x550\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 van 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/R-26324111-1678109862-6010.jpg\" alt=\"R-26324111-1678109862-6010\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 van 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/1200x1200-1-1.jpg\" alt=\"1200x1200 (1)\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-87818fa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"87818fa\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-2fc3a26\" data-id=\"2fc3a26\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-31f4df3 elementor-widget elementor-widget-spacer\" data-id=\"31f4df3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-5ffdec8\" data-id=\"5ffdec8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8c0ba9c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8c0ba9c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-259c4de\" data-id=\"259c4de\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-45da4fd elementor-widget elementor-widget-image\" data-id=\"45da4fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/5054197726453-front-1024x1024.jpg\" class=\"attachment-large size-large wp-image-965\" alt=\"\" srcset=\"https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/5054197726453-front-1024x1024.jpg 1024w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/5054197726453-front-300x300.jpg 300w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/5054197726453-front-150x150.jpg 150w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/5054197726453-front-768x768.jpg 768w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/5054197726453-front-12x12.jpg 12w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/5054197726453-front.jpg 1200w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-7a18e43\" data-id=\"7a18e43\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8a0c056 elementor-widget elementor-widget-text-editor\" data-id=\"8a0c056\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1 translation-block\">Merveilleux enregistrement que celui-ci, compos\u00e9 d\u2019airs d\u2019op\u00e9ra, \u00ab\u00a0canzone\u00a0\u00bb, s\u00e9r\u00e9nades, tarentelles et cantates du Seicento faisant la part belle au compositeur Giovanni Cesare Netti, injustement m\u00e9connu de nos jours. Le programme, dans lequel se c\u00f4toient des classiques du r\u00e9pertoire et pas moins d\u2019une dizaine de premi\u00e8res au disque, s\u00e9duit par son opulence, son intelligence et sa coh\u00e9rence. Drap\u00e9e dans les timbres soyeux et bigarr\u00e9s d\u2019un Il Pomo d\u2019Oro en grande forme, la voix s\u00e9raphine, toujours expressive, et flamboyante \u00e0 point nomm\u00e9, du contralto polonais Jakub J\u00f3zef Orli\u0144ski se prom\u00e8ne avec un naturel et une aisance d\u00e9sarmants, jusque dans les cimes de sa tessiture. Un bijou\u00a0! (Olivier Vrins)<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-45c9636 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"45c9636\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-c80b9a0\" data-id=\"c80b9a0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e9f780c elementor-widget elementor-widget-image\" data-id=\"e9f780c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/71EX0LYu54L._UF10001000_QL80_.jpg\" class=\"attachment-large size-large wp-image-966\" alt=\"\" srcset=\"https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/71EX0LYu54L._UF10001000_QL80_.jpg 1000w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/71EX0LYu54L._UF10001000_QL80_-300x300.jpg 300w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/71EX0LYu54L._UF10001000_QL80_-150x150.jpg 150w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/71EX0LYu54L._UF10001000_QL80_-768x768.jpg 768w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/71EX0LYu54L._UF10001000_QL80_-12x12.jpg 12w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-1ce41e7\" data-id=\"1ce41e7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1d8683d elementor-widget elementor-widget-text-editor\" data-id=\"1d8683d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">Le claveciniste franco-am\u00e9ricain Justin Taylor touche le fabuleux clavecin historique du ch\u00e2teau d\u2019Assas (c. 1730) pour nous offrir un merveilleux programme consacr\u00e9 \u00e0 cette musique italienne tant aim\u00e9e de J.S. Bach au travers de transcriptions d\u2019\u0153uvres orchestrales de compositeurs transalpins (concertos de Vivaldi, mais aussi le magnifique concerto pour hautbois de Benedetto Marcello). Ce Bach baign\u00e9 par le soleil de l\u2019Italie respire \u00e0 chaque mesure la joie de vivre, parfaitement servi par un interpr\u00e8te aussi libre qu\u2019imaginatif. (Patrice Lieberman)<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-de51f9b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"de51f9b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-4c5bcb1\" data-id=\"4c5bcb1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-15565b0 elementor-widget elementor-widget-image\" data-id=\"15565b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/3701624510032-back-1024x1024.jpg\" class=\"attachment-large size-large wp-image-967\" alt=\"\" srcset=\"https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/3701624510032-back-1024x1024.jpg 1024w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/3701624510032-back-300x300.jpg 300w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/3701624510032-back-150x150.jpg 150w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/3701624510032-back-768x768.jpg 768w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/3701624510032-back-12x12.jpg 12w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/3701624510032-back.jpg 1200w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-ef64e36\" data-id=\"ef64e36\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d531f65 elementor-widget elementor-widget-text-editor\" data-id=\"d531f65\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">Lorsqu\u2019elle joue les suites de Bach, Sonia Wieder-Atherton imagine, dit-elle, les mains de Giacometti modelant la terre jusqu\u2019\u00e0 ce qu\u2019apparaisse un visage. Apr\u00e8s les deux premi\u00e8res suites grav\u00e9es en 2021, la violoncelliste franco-am\u00e9ricaine livre les suites n\u00b0 3 et 4, fa\u00e7onnant peu \u00e0 peu ce monument de musique pure avec cette force et ce son qui n\u2019appartiennent qu\u2019\u00e0 elle. Form\u00e9e \u00e0 l\u2019\u00e9cole russe par Natalia Chakhovska\u00efa, fascin\u00e9e par la voix en tant qu\u2019expression vitale, Sonia Wieder-Atherton nous envo\u00fbte une fois de plus. Sa lecture des suites est introspective, spirituelle, avec des graves puissants qui creusent la corde et d\u00e9fient le temps qui passe. Mais ce Bach-l\u00e0 n\u2019est pas dupe de notre humaine finitude, pas davantage que l\u2019archet de Wieder-Atherton, qui d\u00e9roule les phrases en en r\u00e9v\u00e9lant toute la dimension m\u00e9taphysique. (St\u00e9phane Renard)<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9aba914 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9aba914\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-8606c79\" data-id=\"8606c79\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9f85f50 elementor-widget elementor-widget-image\" data-id=\"9f85f50\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/1200x1200-1024x1024.jpg\" class=\"attachment-large size-large wp-image-968\" alt=\"\" srcset=\"https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/1200x1200-1024x1024.jpg 1024w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/1200x1200-300x300.jpg 300w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/1200x1200-150x150.jpg 150w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/1200x1200-768x768.jpg 768w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/1200x1200-12x12.jpg 12w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/1200x1200.jpg 1200w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-70c636d\" data-id=\"70c636d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-11ff4df elementor-widget elementor-widget-text-editor\" data-id=\"11ff4df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">Le Quatuor \u00c9b\u00e8ne accueille l\u2019altiste Antoine Tamestit dans une superbe interpr\u00e9tation des deux plus grands quintettes \u00e0 cordes de Mozart. Pens\u00e9es et travaill\u00e9es jusqu\u2019au moindre d\u00e9tail sans que rien ne sonne jamais p\u00e9dant ou mani\u00e9r\u00e9, ces interpr\u00e9tations r\u00e9ussissent \u00e0 infailliblement p\u00e9n\u00e9trer au c\u0153ur  m\u00eame du myst\u00e8re et de la richesse de cette musique. Une tr\u00e8s grande version. (Patrice Lieberman)<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1abcfef elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1abcfef\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-784a8ee\" data-id=\"784a8ee\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-367980a elementor-widget elementor-widget-image\" data-id=\"367980a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/1200x1200-1-1024x1024.jpg\" class=\"attachment-large size-large wp-image-969\" alt=\"\" srcset=\"https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/1200x1200-1-1024x1024.jpg 1024w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/1200x1200-1-300x300.jpg 300w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/1200x1200-1-150x150.jpg 150w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/1200x1200-1-768x768.jpg 768w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/1200x1200-1-12x12.jpg 12w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/1200x1200-1.jpg 1200w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-42d6b61\" data-id=\"42d6b61\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ddd1395 elementor-widget elementor-widget-text-editor\" data-id=\"ddd1395\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\"><span class=\"s1\">Pappano livre dans cet enregistrement une lecture orchestrale brillante de Puccini, parvenant \u00e0 traduire toutes les nuances de la partition dans les moindres d\u00e9tails. Le ch\u0153ur et l\u2019orchestre sonnent de mani\u00e8re impressionnante, avec par moment de puissants <i>forte<\/i> et <i>fortissimo<\/i> et une sonorit\u00e9 chaleureuse, ronde et transparente dans les sc\u00e8nes chorales. Les pages pour solistes sont \u00e9galement rendues avec brio par l\u2019excellente distribution, les r\u00f4les principaux \u00e9tant d\u00e9volus \u00e0 Sondra Radvanovsky, Jonas Kaufmann et Ermonela Jaho. Ce <i>Turandot <\/i>imp\u00e9rial m\u2019a donn\u00e9 la chair de poule. (Helena Gaudeus)\u00a0<i>Turandot<\/i>\u00a0bezorgde me kippenvel<\/span><span class=\"s2\">. (Helena Gaudeus)<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f27eb2d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f27eb2d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-9868156\" data-id=\"9868156\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e1ee0d1 elementor-widget elementor-widget-image\" data-id=\"e1ee0d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/hilary-hahn-ysaye-6-sonatas-for-violin-solo-op-27-1024x1024.jpg\" class=\"attachment-large size-large wp-image-970\" alt=\"\" srcset=\"https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/hilary-hahn-ysaye-6-sonatas-for-violin-solo-op-27-1024x1024.jpg 1024w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/hilary-hahn-ysaye-6-sonatas-for-violin-solo-op-27-300x300.jpg 300w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/hilary-hahn-ysaye-6-sonatas-for-violin-solo-op-27-150x150.jpg 150w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/hilary-hahn-ysaye-6-sonatas-for-violin-solo-op-27-768x768.jpg 768w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/hilary-hahn-ysaye-6-sonatas-for-violin-solo-op-27-1536x1536.jpg 1536w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/hilary-hahn-ysaye-6-sonatas-for-violin-solo-op-27-12x12.jpg 12w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/hilary-hahn-ysaye-6-sonatas-for-violin-solo-op-27.jpg 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-ca08d36\" data-id=\"ca08d36\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d19fd5f elementor-widget elementor-widget-text-editor\" data-id=\"d19fd5f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1 translation-block\">Avec son cycle de six sonates pour violon seul, qu\u2019il compose \u00e0 partir de 1923, Eug\u00e8ne Ysa\u00ffe consacrait le triomphe de l\u2019\u00e9cole belge du violon. Hilary Hahn c\u00e9l\u00e8bre le centenaire de cette aventure avec une gravure \u00e9poustouflante. La violoniste am\u00e9ricaine, dont le professeur fut l\u2019un des \u00e9l\u00e8ves d\u2019Ysa\u00ffe, se joue de toutes les asp\u00e9rit\u00e9s. Mieux, elle se r\u00e9gale de ces dissonances qui, chez d\u2019autres, ont pu parfois para\u00eetre un peu \u00e2pres. Cette version fera date par la subtilit\u00e9 des phras\u00e9s les plus tendres \u2013 la n\u00b0 2 est un sommet \u2013, l\u2019intelligence du discours et sa musicalit\u00e9 absolue. (St\u00e9phane Renard)<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a395437 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a395437\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-95d5fbc\" data-id=\"95d5fbc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-395eae1 elementor-widget elementor-widget-image\" data-id=\"395eae1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/1200x1200bb-1024x1024.jpg\" class=\"attachment-large size-large wp-image-971\" alt=\"\" srcset=\"https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/1200x1200bb-1024x1024.jpg 1024w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/1200x1200bb-300x300.jpg 300w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/1200x1200bb-150x150.jpg 150w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/1200x1200bb-768x768.jpg 768w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/1200x1200bb-12x12.jpg 12w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/1200x1200bb.jpg 1200w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-2bf4290\" data-id=\"2bf4290\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d2f13f8 elementor-widget elementor-widget-text-editor\" data-id=\"d2f13f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">Non, la pianiste isra\u00e9lienne Yaara Tal est loin d\u2019\u00eatre la premi\u00e8re \u00e0 s\u2019\u00eatre laiss\u00e9 inspirer par la cr\u00e9ation artistique foisonnante de l\u2019entre-deux-guerres. Mais ce bond de cent ans en arri\u00e8re d\u00e9bouche sur un album vraiment unique, nous offrant un r\u00e9pertoire vari\u00e9, plein de d\u00e9couvertes surprenantes, mais toujours coh\u00e9rent. L\u2019interpr\u00e8te r\u00e9ussit \u00e0 tr\u00e8s bien mettre en avant les innovations de l\u2019\u00e9poque\u00a0: la fluidit\u00e9 \u2013 ou le heurt \u2013 des tonalit\u00e9s, les rythmes exub\u00e9rants, les attaques m\u00e9caniques,\u2026 Voici un disque sinc\u00e8re, bien inform\u00e9 et surtout du plus haut int\u00e9r\u00eat\u00a0: exactement ce qu\u2019on attend d\u2019un enregistrement visant \u00e0 ressusciter une p\u00e9riode r\u00e9volue. (Jasper Croonen)<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b890588 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b890588\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-f48a9d3\" data-id=\"f48a9d3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-40956e1 elementor-widget elementor-widget-image\" data-id=\"40956e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/550x550.jpg\" class=\"attachment-large size-large wp-image-972\" alt=\"\" srcset=\"https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/550x550.jpg 550w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/550x550-300x300.jpg 300w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/550x550-150x150.jpg 150w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/550x550-12x12.jpg 12w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-f481888\" data-id=\"f481888\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-96de0a4 elementor-widget elementor-widget-text-editor\" data-id=\"96de0a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\"><span class=\"s1\">Chef prodige, Klaus M\u00e4kel\u00e4 est \u00e0 28 ans seulement chef principal de l\u2019Orchestre philharmonique d\u2019Oslo, artiste associ\u00e9 du Concertgebouw (avant d\u2019en devenir chef principal en 2027), directeur musical de l\u2019Orchestre de Paris et tout juste nomm\u00e9 directeur musical du Chicago Symphony Orchestra \u00e0 compter de la saison 2027-2028. Avec l\u2019Orchestre de Paris, ce fut \u00ab\u00a0un coup de foudre imm\u00e9diat\u00a0\u00bb. Une relation solide, de confiance aussi, qui lui permet de construire une vision diablement vivante de ces deux pi\u00e8ces iconiques de Stravinsky. Sous la direction de Klaus M\u00e4kel\u00e4, mu\u00e9 par une \u00e9nergie sans faille, la musique virevolte, d\u00e9voile ses multiples nuances, avec intensit\u00e9 mais aussi une certaine force tranquille. \u00c0 l\u2019image du chef, d\u00e9sormais incontournable. (Ga\u00eblle Moury)<\/span><span class=\"s2\">. (Ga\u00eblle Moury) <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-51ea966 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"51ea966\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-d3d6460\" data-id=\"d3d6460\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-56ee770 elementor-widget elementor-widget-image\" data-id=\"56ee770\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/R-26324111-1678109862-6010.jpg\" class=\"attachment-large size-large wp-image-973\" alt=\"\" srcset=\"https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/R-26324111-1678109862-6010.jpg 400w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/R-26324111-1678109862-6010-300x300.jpg 300w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/R-26324111-1678109862-6010-150x150.jpg 150w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/R-26324111-1678109862-6010-12x12.jpg 12w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-2ecee55\" data-id=\"2ecee55\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-08935ce elementor-widget elementor-widget-text-editor\" data-id=\"08935ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">Poulencs micro-opera <i>La voix humaine<\/i> Le micro-op\u00e9ra <i>La voix humaine<\/i> de Poulenc est une partition pleine de surprises sur tous les plans. Le compositeur alterne un chant proche de la parole et une l\u00e9g\u00e8ret\u00e9 ludique avec des \u00e9pisodes dramatiques cr\u00e9ant une musique pleine de mots non prononc\u00e9s et de silences qui en disent long. Mais l\u2019essentiel est la solitude de l\u2019interpr\u00e8te. L\u2019auditeur n\u2019entend en effet que la femme qui est au t\u00e9l\u00e9phone avec son ex-mari. V\u00e9ronique Gens s\u2019est sentie enfin pr\u00eate \u00e0 d\u00e9crocher le combin\u00e9 \u2013 et comment. Son ph\u00e9nom\u00e9nal sens du th\u00e9\u00e2tre fait que cette trag\u00e9dienne nous entra\u00eene et nous subjugue dans ce dialogue \u00e0 une voix. (Jasper Croonen)<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d0d883e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d0d883e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-361d3fd\" data-id=\"361d3fd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b7b69aa elementor-widget elementor-widget-image\" data-id=\"b7b69aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/1200x1200-1-1-1024x1024.jpg\" class=\"attachment-large size-large wp-image-974\" alt=\"\" srcset=\"https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/1200x1200-1-1-1024x1024.jpg 1024w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/1200x1200-1-1-300x300.jpg 300w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/1200x1200-1-1-150x150.jpg 150w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/1200x1200-1-1-768x768.jpg 768w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/1200x1200-1-1-12x12.jpg 12w, https:\/\/muziekpers-pressemusicale.be\/wp-content\/uploads\/2024\/04\/1200x1200-1-1.jpg 1200w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-bcb20e7\" data-id=\"bcb20e7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e074b3d elementor-widget elementor-widget-text-editor\" data-id=\"e074b3d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\"><span class=\"s1\">Arvo P\u00e4rt staat tegenwoordig haast gelijk aan de Estse koormuziek. Maar hij is niet de enige Estse componist van formaat. Hoewel Tormis in onze streken minder bekend is, koestert de Estse dirigent T\u00f5nu Kaljuste een diepe bewondering voor hem. Kaljuste heeft samen met het Ests Filharmonisch Kamerkoor en het Tallinn Kamerorkest het omvangrijke repertoire van hem opgenomen.\u00a0<i>Reminiscentiae<\/i> maakt deel uit van Kaljustes missie om Tormis&#8217; werk te eren. Het repertoire valt op door zijn eenvoudige harmonie\u00ebn, waardoor de melodie\u00ebn bijzonder naar voren komen. Dit album kenmerkt zich door zijn intrigerende virtuoze <\/span><span class=\"s2\">opstellingen<\/span><span class=\"s1\">, navigerend op de delicate grens tussen het vreemde en het vertrouwde<\/span><span class=\"s3\">. (Helena Gaudeus)<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-9a49681 elementor-widget elementor-widget-spacer\" data-id=\"9a49681\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-c518b13\" data-id=\"c518b13\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-76a85ea elementor-widget elementor-widget-spacer\" data-id=\"76a85ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-65204cb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"65204cb\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cfbfb7c\" data-id=\"cfbfb7c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-449d3bd elementor-widget elementor-widget-heading\" data-id=\"449d3bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Composition du jury<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-424b3c7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"424b3c7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-83b7a5f\" data-id=\"83b7a5f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8174c48 elementor-widget elementor-widget-text-editor\" data-id=\"8174c48\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Roger Creyf<\/strong> <br \/>(Klassiek Centraal)<\/p><p><strong>Jasper Croonen<\/strong> <br \/>(De Standaard, BRUZZ)<\/p><p><strong>Helena Gaudeus<\/strong> <br \/>(Klassiek Centraal)<\/p><p><strong>Patrice Lieberman<\/strong> <br \/>(Pr\u00e9sident de l\u2019Union de la Presse Musicale Belge, Crescendo)<\/p><p class=\"p1\"><strong>Ga\u00eblle Moury<br \/><\/strong>(Le Soir)<\/p><p><strong>St\u00e9phane Renard<br \/><\/strong>(L\u2019\u00c9cho)<\/p><p><strong>Olivier Vrins <\/strong><br \/>(Crescendo)<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Cecilia Prijzen | 2023 Jonge Musicus van het Jaar Preselectie voor de Prijs van de Jonge Musicus van het Jaar 2023 (FR) De Prijs van de Jonge Musicus van het Jaar wordt afwisselend toegekend aan een Nederlandstalige en een Franstalige of Duitstalige musicus. Fiona &amp; Chiara Alaimo, piano Pierre Fontenelle, cello Juliette Gauthier, harp Maya [&hellip;]<\/p>","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-945","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/muziekpers-pressemusicale.be\/fr\/wp-json\/wp\/v2\/pages\/945","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/muziekpers-pressemusicale.be\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/muziekpers-pressemusicale.be\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/muziekpers-pressemusicale.be\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/muziekpers-pressemusicale.be\/fr\/wp-json\/wp\/v2\/comments?post=945"}],"version-history":[{"count":55,"href":"https:\/\/muziekpers-pressemusicale.be\/fr\/wp-json\/wp\/v2\/pages\/945\/revisions"}],"predecessor-version":[{"id":1927,"href":"https:\/\/muziekpers-pressemusicale.be\/fr\/wp-json\/wp\/v2\/pages\/945\/revisions\/1927"}],"wp:attachment":[{"href":"https:\/\/muziekpers-pressemusicale.be\/fr\/wp-json\/wp\/v2\/media?parent=945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}